{"id":1764,"date":"2009-02-22T12:59:15","date_gmt":"2009-02-22T10:59:15","guid":{"rendered":"http:\/\/www.miguelmoreno.org\/blog\/?p=1764"},"modified":"2009-02-22T12:59:15","modified_gmt":"2009-02-22T10:59:15","slug":"programa-del-carnaval-de-cadiz-domingo-22-de-febrero","status":"publish","type":"post","link":"https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/","title":{"rendered":"Programa del Carnaval de C\u00e1diz &#8211; domingo 22 de febrero"},"content":{"rendered":"<p>Domingo 22 de febrero<br \/>\n\u00b7 CARRUSEL COROS<br \/>\nHora Salida: 14.00 h. &#8211; Hora Final: 19.00 h<\/p>\n<p>RECORRIDO A<br \/>\nSalida Plaza de Candelaria &#8211; Monta\u00f1\u00e9s &#8211; Plaza del Palillero &#8211; Columela &#8211; Plaza de las Flores &#8211; Barri\u00e9 &#8211; Sacramento &#8211; Londres &#8211; Hospital de Mujeres.<\/p>\n<p>RECORRIDO B<br \/>\nSalida Plaza de Candelaria &#8211; Monta\u00f1\u00e9s &#8211; Plaza del Palillero &#8211; Novena &#8211; Ancha &#8211; San Jos\u00e9 &#8211; Final Plaza de Mina.<\/p>\n<p>RECORRIDO C<br \/>\nSalida Plaza de Mina (junto al Museo) &#8211; Vuelta a la Plaza de Mina &#8211; Tinte &#8211; Plaza de San Francisco &#8211; San Francisco &#8211; Nueva.<br \/>\n\u00b7 CABALGATA MAGNA<br \/>\nHora Salida: 18.00 h.<br \/>\nItinerario: Glorieta Ingeniero de la Cierva &#8211; Avda. Cayetano del Toro &#8211; Avda. Ana de Viya &#8211; Avda. de Andaluc\u00eda &#8211; Puertas de Tierra (vuelta completa) &#8211; Final en el antiguo Banco de Espa\u00f1a.<\/p>\n<p>\u00b7 FUEGOS ARTIFICIALES<br \/>\n23.00 H CASTILLO SAN SEBASTIAN<\/p>\n<p>\u00b7 BAILES CARPAS 23.00 H.<br \/>\nANTIGUO PARQUE DE BOMBEROS<br \/>\nSANTA B\u00c1RBARA<br \/>\nBALUARTE CANDELARIA<\/p>\n<p>Otros actos:<\/p>\n<p>XXIV Exposici\u00f3n Filat\u00e9lica<br \/>\nSociedad Filat\u00e9lica Gaditana. Centro Integral de la Mujer-Plaza del Palillero<\/p>\n<p>-Federaci\u00f3n Provincial de Pe\u00f1as Gaditanas.<br \/>\nPlaza de San Francisco.-Actuaciones de Agrupaciones Carnavalescas<\/p>\n<p>-Pe\u00f1a Carnavalesca \u00abLA PALMA EL PURRI DE C\u00c1DIZ\u00bb<br \/>\nC\/ Virgen de la Palma, 21- III Concurso de Romanceros<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domingo 22 de febrero \u00b7 CARRUSEL COROS Hora Salida: 14.00 h. &#8211; Hora Final: 19.00 h RECORRIDO A Salida Plaza de Candelaria &#8211; Monta\u00f1\u00e9s &#8211; Plaza del Palillero &#8211; Columela &#8211; Plaza de las Flores &#8211; Barri\u00e9 &#8211; Sacramento &#8211; Londres &#8211; Hospital de Mujeres. RECORRIDO B Salida Plaza de Candelaria &#8211; Monta\u00f1\u00e9s &#8211; Plaza &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Programa del Carnaval de C\u00e1diz &#8211; domingo 22 de febrero\" class=\"read-more button\" href=\"https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/#more-1764\" aria-label=\"Leer m\u00e1s sobre Programa del Carnaval de C\u00e1diz &#8211; domingo 22 de febrero\">M\u00e1s informaci\u00f3n<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1764","post","type-post","status-publish","format-standard","hentry","category-general","masonry-post","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Programa del Carnaval de C\u00e1diz - domingo 22 de febrero<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Se llama copla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/\",\"url\":\"https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/\",\"name\":\"Programa del Carnaval de C\u00e1diz - domingo 22 de febrero\",\"isPartOf\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#website\"},\"datePublished\":\"2009-02-22T10:59:15+00:00\",\"author\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5\"},\"breadcrumb\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/miguelmoreno.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programa del Carnaval de C\u00e1diz &#8211; domingo 22 de febrero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#website\",\"url\":\"https:\/\/miguelmoreno.org\/blog\/\",\"name\":\"El Blog del Sur\",\"description\":\"Cultura, conciertos, ferias, coplas...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/miguelmoreno.org\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5\",\"name\":\"Se llama copla\",\"sameAs\":[\"https:\/\/miguelmoreno.org\/blog\",\"https:\/\/x.com\/coplasandalucia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programa del Carnaval de C\u00e1diz - domingo 22 de febrero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/","twitter_misc":{"Escrito por":"Se llama copla","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/","url":"https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/","name":"Programa del Carnaval de C\u00e1diz - domingo 22 de febrero","isPartOf":{"@id":"https:\/\/miguelmoreno.org\/blog\/#website"},"datePublished":"2009-02-22T10:59:15+00:00","author":{"@id":"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5"},"breadcrumb":{"@id":"https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/miguelmoreno.org\/blog\/programa-del-carnaval-de-cadiz-domingo-22-de-febrero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/miguelmoreno.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Programa del Carnaval de C\u00e1diz &#8211; domingo 22 de febrero"}]},{"@type":"WebSite","@id":"https:\/\/miguelmoreno.org\/blog\/#website","url":"https:\/\/miguelmoreno.org\/blog\/","name":"El Blog del Sur","description":"Cultura, conciertos, ferias, coplas...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miguelmoreno.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5","name":"Se llama copla","sameAs":["https:\/\/miguelmoreno.org\/blog","https:\/\/x.com\/coplasandalucia"]}]}},"_links":{"self":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts\/1764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/comments?post=1764"}],"version-history":[{"count":0,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts\/1764\/revisions"}],"wp:attachment":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/media?parent=1764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/categories?post=1764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/tags?post=1764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}