{"id":2177,"date":"2009-06-06T23:42:02","date_gmt":"2009-06-06T21:42:02","guid":{"rendered":"http:\/\/www.miguelmoreno.org\/blog\/?p=2177"},"modified":"2015-06-04T00:16:39","modified_gmt":"2015-06-03T22:16:39","slug":"subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita","status":"publish","type":"post","link":"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/","title":{"rendered":"Subida de la Virgen de los Remedios de Cartama a su Ermita"},"content":{"rendered":"<figure id=\"attachment_2183\" aria-describedby=\"caption-attachment-2183\" style=\"width: 309px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.miguelmoreno.org\/blog\/?attachment_id=2183\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2183\" title=\"cara_virgen_remedios\" src=\"https:\/\/www.miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/cara_virgen_remedios.jpg\" alt=\"Detalle de la Virgen de los Remedios de cartama\" width=\"319\" height=\"448\" srcset=\"https:\/\/miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/cara_virgen_remedios.jpg 319w, https:\/\/miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/cara_virgen_remedios-214x300.jpg 214w\" sizes=\"auto, (max-width: 319px) 100vw, 319px\" \/><\/a><figcaption id=\"caption-attachment-2183\" class=\"wp-caption-text\">Virgen de Los Remedios<\/figcaption><\/figure>\n<p>Ma\u00f1ana domngo 7 de junio tendr\u00e1 lugar \u00abla subia\u00bb de la Virgen de los Remedios de Cartama, desde la Iglesia de San Pedro hasta su Ermita.<\/p>\n<figure id=\"attachment_2185\" aria-describedby=\"caption-attachment-2185\" style=\"width: 438px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2185\" title=\"ermita_cartama\" src=\"https:\/\/www.miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/ermita_cartama.jpg\" alt=\"Ermita de Nuestra Se\u00f1ora de los Remedios, en C\u00e1rtama\" width=\"448\" height=\"336\" srcset=\"https:\/\/miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/ermita_cartama.jpg 448w, https:\/\/miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/ermita_cartama-300x224.jpg 300w\" sizes=\"auto, (max-width: 448px) 100vw, 448px\" \/><figcaption id=\"caption-attachment-2185\" class=\"wp-caption-text\">Ermita de Nuestra Se\u00f1ora de los Remedios, en C\u00e1rtama<\/figcaption><\/figure>\n<p>Cumpliendo la tradici\u00f3n de cada primer domingo de junio, ma\u00f1ana la Virgen de Los Remedios, \u00a0patrona de Cartama, iniciara su camino de vuelta a su Ermita. La salida \u00a0ser\u00e1 despues de la misa de las 7 de la tarde, en ese momento la Virgencita de Cartama ascender\u00e1 por las cuestas del camino que lleva hasta su Ermita, junto a las murallas del castillo.<\/p>\n<figure id=\"attachment_2186\" aria-describedby=\"caption-attachment-2186\" style=\"width: 326px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.miguelmoreno.org\/blog\/?attachment_id=2186\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2186\" title=\"virgen_remedios_cartama\" src=\"https:\/\/www.miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/virgen_remedios_cartama.jpg\" alt=\"Nuestra Se\u00f1ora de los Remedios\" width=\"336\" height=\"446\" srcset=\"https:\/\/miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/virgen_remedios_cartama.jpg 336w, https:\/\/miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/virgen_remedios_cartama-226x300.jpg 226w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><figcaption id=\"caption-attachment-2186\" class=\"wp-caption-text\">Nuestra Se\u00f1ora de los Remedios<\/figcaption><\/figure>\n<p>Hoy hemos tenido la oportunidad de ver a la \u00abVirgen de Cartama\u00bb en la Iglesia donde \u00abPepe el de la Iglesia\u00bb nos ha contado varios detalles sobre la restauraci\u00f3n de dicha iglesia y sobre la f\u00e9 que tantisima gente le tiene a esta virgen tan peque\u00f1ita y tan milagrosa para tantisima gente.<\/p>\n<figure id=\"attachment_2184\" aria-describedby=\"caption-attachment-2184\" style=\"width: 326px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.miguelmoreno.org\/blog\/?attachment_id=2184\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2184\" title=\"trono_virgen_cartama\" src=\"https:\/\/www.miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/trono_virgen_cartama.jpg\" alt=\"Trono de Nuestra Se\u00f1ora de los Remedios\" width=\"336\" height=\"448\" srcset=\"https:\/\/miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/trono_virgen_cartama.jpg 336w, https:\/\/miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/trono_virgen_cartama-224x300.jpg 224w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><figcaption id=\"caption-attachment-2184\" class=\"wp-caption-text\">Trono de Nuestra Se\u00f1ora de los Remedios<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ma\u00f1ana domngo 7 de junio tendr\u00e1 lugar \u00abla subia\u00bb de la Virgen de los Remedios de Cartama, desde la Iglesia de San Pedro hasta su Ermita. Cumpliendo la tradici\u00f3n de cada primer domingo de junio, ma\u00f1ana la Virgen de Los Remedios, \u00a0patrona de Cartama, iniciara su camino de vuelta a su Ermita. La salida \u00a0ser\u00e1 &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Subida de la Virgen de los Remedios de Cartama a su Ermita\" class=\"read-more button\" href=\"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/#more-2177\" aria-label=\"Leer m\u00e1s sobre Subida de la Virgen de los Remedios de Cartama a su Ermita\">M\u00e1s informaci\u00f3n<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2177","post","type-post","status-publish","format-standard","hentry","category-general","masonry-post","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Subida de la Virgen de los Remedios de Cartama a su Ermita<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Se llama copla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/\",\"url\":\"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/\",\"name\":\"Subida de la Virgen de los Remedios de Cartama a su Ermita\",\"isPartOf\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/cara_virgen_remedios.jpg\",\"datePublished\":\"2009-06-06T21:42:02+00:00\",\"dateModified\":\"2015-06-03T22:16:39+00:00\",\"author\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5\"},\"breadcrumb\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/#primaryimage\",\"url\":\"https:\/\/www.miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/cara_virgen_remedios.jpg\",\"contentUrl\":\"https:\/\/www.miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/cara_virgen_remedios.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/miguelmoreno.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Subida de la Virgen de los Remedios de Cartama a su Ermita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#website\",\"url\":\"https:\/\/miguelmoreno.org\/blog\/\",\"name\":\"El Blog del Sur\",\"description\":\"Cultura, conciertos, ferias, coplas...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/miguelmoreno.org\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5\",\"name\":\"Se llama copla\",\"sameAs\":[\"https:\/\/miguelmoreno.org\/blog\",\"https:\/\/x.com\/coplasandalucia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Subida de la Virgen de los Remedios de Cartama a su Ermita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/","twitter_misc":{"Escrito por":"Se llama copla","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/","url":"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/","name":"Subida de la Virgen de los Remedios de Cartama a su Ermita","isPartOf":{"@id":"https:\/\/miguelmoreno.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/#primaryimage"},"image":{"@id":"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/cara_virgen_remedios.jpg","datePublished":"2009-06-06T21:42:02+00:00","dateModified":"2015-06-03T22:16:39+00:00","author":{"@id":"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5"},"breadcrumb":{"@id":"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/#primaryimage","url":"https:\/\/www.miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/cara_virgen_remedios.jpg","contentUrl":"https:\/\/www.miguelmoreno.org\/blog\/wp-content\/uploads\/2009\/06\/cara_virgen_remedios.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/miguelmoreno.org\/blog\/subida-de-la-virgen-de-los-remedios-de-cartama-a-su-ermita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/miguelmoreno.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Subida de la Virgen de los Remedios de Cartama a su Ermita"}]},{"@type":"WebSite","@id":"https:\/\/miguelmoreno.org\/blog\/#website","url":"https:\/\/miguelmoreno.org\/blog\/","name":"El Blog del Sur","description":"Cultura, conciertos, ferias, coplas...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miguelmoreno.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5","name":"Se llama copla","sameAs":["https:\/\/miguelmoreno.org\/blog","https:\/\/x.com\/coplasandalucia"]}]}},"_links":{"self":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts\/2177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/comments?post=2177"}],"version-history":[{"count":0,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts\/2177\/revisions"}],"wp:attachment":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/media?parent=2177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/categories?post=2177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/tags?post=2177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}