{"id":3676,"date":"2010-05-29T12:39:05","date_gmt":"2010-05-29T10:39:05","guid":{"rendered":"http:\/\/www.miguelmoreno.org\/blog\/?p=3676"},"modified":"2010-05-29T12:39:05","modified_gmt":"2010-05-29T10:39:05","slug":"dias-de-radio-en-malaga","status":"publish","type":"post","link":"https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/","title":{"rendered":"Dias de Radio en Malaga"},"content":{"rendered":"<p>La Diputaci\u00f3n de M\u00e1laga, en colaboraci\u00f3n con la Facultad de Ciencias de la Comunicaci\u00f3n de la Universidad de M\u00e1laga y el Patronato Provincial de Turismo Costa del Sol, llevar\u00e1 al Auditorio de la calle Pac\u00edfico a partir del lunes la <strong>emisi\u00f3n en directo<\/strong> de algunos de los principales programas de radio nacionales, como son los de <strong>Juan Ram\u00f3n Lucas (RNE), \u00c1ngels Barcel\u00f3 (Cadena SER), Tom Mart\u00edn Ben\u00edtez (Canal Sur Radio), F\u00e9lix Madero (Punto Radio) y Nacho Villa (COPE),<\/strong> que realizar\u00e1n en directo sus programas.<\/p>\n<p><!--more-->Ser\u00e1 dentro de las jornadas D\u00edas de Radio, que incluir\u00e1n adem\u00e1s conferencias, coloquios y proyecciones, y cuyo objetivo es rendir homenaje a este fundamental medio de comunicaci\u00f3n con motivo de la celebraci\u00f3n del 90 aniversario de la radio comercial en el mundo.<\/p>\n<p>Adem\u00e1s, cada emisora contar\u00e1 con sus propios invitados. As\u00ed, el pr\u00f3ximo lunes, Juan Ram\u00f3n Lucas contar\u00e1 en su programa \u2018En d\u00edas como hoy&#8217;, de Radio Nacional de Espa\u00f1a, con la actuaci\u00f3n en directo de Diana Navarro y Danza Invisible, entre otros.<\/p>\n<p>La entrada es libre y gratuita hasta completar aforo.<\/p>\n<p>PROGRAMACI\u00d3N D\u00cdAS DE RADIO<\/p>\n<p>LUNES, 31 DE MAYO<\/p>\n<p>8.00-12.00 h. Emisi\u00f3n en directo \u2018En d\u00edas como hoy&#8217;, presentado por Juan Ram\u00f3n Lucas, Radio Nacional de Espa\u00f1a.<\/p>\n<p>12.30 h. Inauguraci\u00f3n de las jornadas a cargo del presidente de la Diputaci\u00f3n de M\u00e1laga, Salvador Pend\u00f3n y un representante de la Universidad de M\u00e1laga.<\/p>\n<p>13.00-15.00 h. Conferencia a cargo de Juan Ram\u00f3n Lucas, presentado por el periodista Rafael Rodr\u00edguez.<\/p>\n<p>18.30-20.30 h. Conferencia a cargo de la periodista Angels Barcel\u00f3, presentada por Juan Francisco Guti\u00e9rrez, profesor de la Facultad de Ciencias de la Comunicaci\u00f3n de la UMA.<\/p>\n<p>21.00-24.00 h. Emisi\u00f3n en directo del programa \u2018Hora 25&#8242;, presentado por Angels Barcel\u00f3, cadena SER.<\/p>\n<p>MARTES, 1 DE JUNIO<\/p>\n<p>8.00-11.00 h. Emisi\u00f3n en directo de \u2018La hora de Andaluc\u00eda&#8217;, presentado por Tom Mart\u00edn Ben\u00edtez, Canal Sur Radio.<\/p>\n<p>11.30-13.30 h. Conferencia a cargo de Tom Mart\u00edn Ben\u00edtez, presentado por el director de la delegaci\u00f3n de Cultura de la Diputaci\u00f3n de M\u00e1laga, Juan Antonio Vigar.<\/p>\n<p>MI\u00c9RCOLES, 2 DE JUNIO<\/p>\n<p>6.00-9.30 h. Emisi\u00f3n en directo de \u2018Protagonistas con F\u00e9lix Madero&#8217;, Punto radio.<\/p>\n<p>10.00-12.00 h. Conferencia a cargo de F\u00e9lix Madero, presentado por Manuel Chaparro, profesor de la Facultad de Ciencias de la Comunicaci\u00f3n de la UMA.<\/p>\n<p>JUEVES, 3 DE JUNIO<\/p>\n<p>6.00-10.00 h. Emisi\u00f3n en directo de \u2018La ma\u00f1ana&#8217;, presentado por Nacho Villa, cadena COPE.<\/p>\n<p>10.30-12.30 h. Conferencia a cargo de Nacho Villa, presentado por Teresa Vera, profesora de la Facultad de Ciencias de la Comunicaci\u00f3n de la UMA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Diputaci\u00f3n de M\u00e1laga, en colaboraci\u00f3n con la Facultad de Ciencias de la Comunicaci\u00f3n de la Universidad de M\u00e1laga y el Patronato Provincial de Turismo Costa del Sol, llevar\u00e1 al Auditorio de la calle Pac\u00edfico a partir del lunes la emisi\u00f3n en directo de algunos de los principales programas de radio nacionales, como son los &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Dias de Radio en Malaga\" class=\"read-more button\" href=\"https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/#more-3676\" aria-label=\"Leer m\u00e1s sobre Dias de Radio en Malaga\">M\u00e1s informaci\u00f3n<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3676","post","type-post","status-publish","format-standard","hentry","category-general","masonry-post","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dias de Radio en Malaga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Se llama copla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/\",\"url\":\"https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/\",\"name\":\"Dias de Radio en Malaga\",\"isPartOf\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#website\"},\"datePublished\":\"2010-05-29T10:39:05+00:00\",\"author\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5\"},\"breadcrumb\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/miguelmoreno.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dias de Radio en Malaga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#website\",\"url\":\"https:\/\/miguelmoreno.org\/blog\/\",\"name\":\"El Blog del Sur\",\"description\":\"Cultura, conciertos, ferias, coplas...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/miguelmoreno.org\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5\",\"name\":\"Se llama copla\",\"sameAs\":[\"https:\/\/miguelmoreno.org\/blog\",\"https:\/\/x.com\/coplasandalucia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dias de Radio en Malaga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/","twitter_misc":{"Escrito por":"Se llama copla","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/","url":"https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/","name":"Dias de Radio en Malaga","isPartOf":{"@id":"https:\/\/miguelmoreno.org\/blog\/#website"},"datePublished":"2010-05-29T10:39:05+00:00","author":{"@id":"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5"},"breadcrumb":{"@id":"https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/miguelmoreno.org\/blog\/dias-de-radio-en-malaga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/miguelmoreno.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Dias de Radio en Malaga"}]},{"@type":"WebSite","@id":"https:\/\/miguelmoreno.org\/blog\/#website","url":"https:\/\/miguelmoreno.org\/blog\/","name":"El Blog del Sur","description":"Cultura, conciertos, ferias, coplas...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miguelmoreno.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5","name":"Se llama copla","sameAs":["https:\/\/miguelmoreno.org\/blog","https:\/\/x.com\/coplasandalucia"]}]}},"_links":{"self":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts\/3676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/comments?post=3676"}],"version-history":[{"count":0,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts\/3676\/revisions"}],"wp:attachment":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/media?parent=3676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/categories?post=3676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/tags?post=3676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}