{"id":3779,"date":"2010-07-05T09:31:57","date_gmt":"2010-07-05T07:31:57","guid":{"rendered":"http:\/\/www.miguelmoreno.org\/blog\/?p=3779"},"modified":"2010-07-05T09:31:57","modified_gmt":"2010-07-05T07:31:57","slug":"una-playa-de-cine-en-cadiz","status":"publish","type":"post","link":"https:\/\/miguelmoreno.org\/blog\/una-playa-de-cine-en-cadiz\/","title":{"rendered":"Una Playa de Cine en Cadiz"},"content":{"rendered":"<p>El programa \u00abUna playa de Cine\u00bb de C\u00e1diz se celebra durante los meses de verano. Todos los s\u00e1bados por la noche a partir del pr\u00f3ximo s\u00e1bado, 3 de julio, a las 22,30 horas, en el m\u00f3dulo central de la playa de La Victoria, con la pel\u00edcula \u2018Slumdog Millonaire&#8217;.<\/p>\n<p><!--more--><!--more-->El programa continuar\u00e1 todos los s\u00e1bados, proyect\u00e1ndose las siguientes pel\u00edculas:<\/p>\n<p>Julio<\/p>\n<p>S\u00e1bado 3 \u00abSlumdog Millonaire\u00bb<\/p>\n<p>S\u00e1bado 10 \u00ab007 Quantum of Solace\u00bb<\/p>\n<p>S\u00e1bado 17 \u00abNoche en el museo 2\u00bb<\/p>\n<p>S\u00e1bado 24 \u00abEl lince perdido\u00bb<\/p>\n<p>S\u00e1bado 31 \u00abGran Torino\u00bb<\/p>\n<p>Agosto<\/p>\n<p>S\u00e1bado 14 \u00abTransformers\u00bb<\/p>\n<p>S\u00e1bado 21 \u00abMonstruos contra alien\u00edgenas\u00bb<\/p>\n<p>S\u00e1bado 28 \u00abLa proposici\u00f3n\u00bb<\/p>\n<p>* El s\u00e1bado 7 no se proyecta por ser el d\u00eda de la final del Trofeo Carranza, con sus correspondientes barbacoas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El programa \u00abUna playa de Cine\u00bb de C\u00e1diz se celebra durante los meses de verano. Todos los s\u00e1bados por la noche a partir del pr\u00f3ximo s\u00e1bado, 3 de julio, a las 22,30 horas, en el m\u00f3dulo central de la playa de La Victoria, con la pel\u00edcula \u2018Slumdog Millonaire&#8217;.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[116,174],"class_list":["post-3779","post","type-post","status-publish","format-standard","hentry","category-general","tag-cadiz","tag-cine","masonry-post","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una Playa de Cine en Cadiz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miguelmoreno.org\/blog\/una-playa-de-cine-en-cadiz\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Se llama copla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/una-playa-de-cine-en-cadiz\/\",\"url\":\"https:\/\/miguelmoreno.org\/blog\/una-playa-de-cine-en-cadiz\/\",\"name\":\"Una Playa de Cine en Cadiz\",\"isPartOf\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#website\"},\"datePublished\":\"2010-07-05T07:31:57+00:00\",\"author\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5\"},\"breadcrumb\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/una-playa-de-cine-en-cadiz\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/miguelmoreno.org\/blog\/una-playa-de-cine-en-cadiz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/una-playa-de-cine-en-cadiz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/miguelmoreno.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una Playa de Cine en Cadiz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#website\",\"url\":\"https:\/\/miguelmoreno.org\/blog\/\",\"name\":\"El Blog del Sur\",\"description\":\"Cultura, conciertos, ferias, coplas...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/miguelmoreno.org\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5\",\"name\":\"Se llama copla\",\"sameAs\":[\"https:\/\/miguelmoreno.org\/blog\",\"https:\/\/x.com\/coplasandalucia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una Playa de Cine en Cadiz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miguelmoreno.org\/blog\/una-playa-de-cine-en-cadiz\/","twitter_misc":{"Escrito por":"Se llama copla","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/miguelmoreno.org\/blog\/una-playa-de-cine-en-cadiz\/","url":"https:\/\/miguelmoreno.org\/blog\/una-playa-de-cine-en-cadiz\/","name":"Una Playa de Cine en Cadiz","isPartOf":{"@id":"https:\/\/miguelmoreno.org\/blog\/#website"},"datePublished":"2010-07-05T07:31:57+00:00","author":{"@id":"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5"},"breadcrumb":{"@id":"https:\/\/miguelmoreno.org\/blog\/una-playa-de-cine-en-cadiz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miguelmoreno.org\/blog\/una-playa-de-cine-en-cadiz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/miguelmoreno.org\/blog\/una-playa-de-cine-en-cadiz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/miguelmoreno.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Una Playa de Cine en Cadiz"}]},{"@type":"WebSite","@id":"https:\/\/miguelmoreno.org\/blog\/#website","url":"https:\/\/miguelmoreno.org\/blog\/","name":"El Blog del Sur","description":"Cultura, conciertos, ferias, coplas...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miguelmoreno.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5","name":"Se llama copla","sameAs":["https:\/\/miguelmoreno.org\/blog","https:\/\/x.com\/coplasandalucia"]}]}},"_links":{"self":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts\/3779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/comments?post=3779"}],"version-history":[{"count":0,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts\/3779\/revisions"}],"wp:attachment":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/media?parent=3779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/categories?post=3779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/tags?post=3779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}