{"id":5235,"date":"2011-11-18T14:17:14","date_gmt":"2011-11-18T12:17:14","guid":{"rendered":"http:\/\/www.miguelmoreno.org\/blog\/?p=5235"},"modified":"2011-11-18T14:17:14","modified_gmt":"2011-11-18T12:17:14","slug":"primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia","status":"publish","type":"post","link":"https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/","title":{"rendered":"Primer encuentro de pintura al vino en la Regi\u00f3n de Murcia"},"content":{"rendered":"<p>La Asociaci\u00f3n Murciana de Cr\u00edticos de Arte, la Fundaci\u00f3n Fuentes\u2010Vicente y la Cofrad\u00eda del Vino Reino de la Monastrell promueven un \u201cPrimer encuentro de pintura al vino en la Regi\u00f3n de Murcia\u201d, que se desarrollar\u00e1 en el Palacete de la Seda, en la pedan\u00eda murciana de Santa Cruz, durante la jornada del 19 de noviembre.<\/p>\n<p>Un total de 11 galer\u00edas de arte de la regi\u00f3n de Murcia participan en el encuentro, salas que a su vez han invitado, respectivamente, a dos de sus artistas, quienes pintar\u00e1n sobre papel motivos relacionados con el \u00e1mbito del vino, sin sujeci\u00f3n alguna a estilo, t\u00e9cnica, y vali\u00e9ndose \u00fanicamente de materiales \u00edntimamente relacionados con el vino.<\/p>\n<p><!--more--><\/p>\n<p>Las galer\u00edas y artistas participantes son: Art Nueve, con Sergio Porl\u00e1n y Ana Mart\u00ednez; Babel, con Torregar y Crist\u00f3bal P\u00e9rez Garc\u00eda (Toval); Bisel, con Antonio G\u00f3mez Ribelles y Dora Catarineu; Chys, con Antonio Martinez Mengual y Almagro; Detr\u00e1s del Rollo, con \u00a0M. Salazar y Katarzyna Rogowicz; Gigarpe, con Laura Molina y \u00c1ngel Mac\u00eda; Kim Gallery, con Marcos Amor\u00f3s y Miguel Alem\u00e1n; La Aurora, con Manuel Perez \u00a0y Emilio Pascual; La Ribera, con Mart\u00ednez Lax y Marta Melacho; Progreso<\/p>\n<p>80, con Alfonso Escudero y Ricardo Escavy; y Romea 3, con Jos\u00e9 M\u00aa Garc\u00eda Herrero y Rafael Pic\u00f3.<\/p>\n<p>Los veintidos artistas desarrollar\u00e1n su creatividad prescindiendo de materiales convencionales, utilizando vinos y uvas de diferente color y cuerpo, tierras, sarmientos, hojas de vid, hollejos y taninos. Trabajar\u00e1n individualmente en grandes mesas dispuestas en \u00a0los \u00a0salones de la \u00a0hoster\u00eda Palacete de la Seda.<\/p>\n<p>Los trabajos se desarrollar\u00e1n durante la ma\u00f1ana y la tarde, quedar\u00e1n expuestos en la sala y posteriormente la obra ser\u00e1 llevada a otros espacios para su exhibici\u00f3n p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asociaci\u00f3n Murciana de Cr\u00edticos de Arte, la Fundaci\u00f3n Fuentes\u2010Vicente y la Cofrad\u00eda del Vino Reino de la Monastrell promueven un \u201cPrimer encuentro de pintura al vino en la Regi\u00f3n de Murcia\u201d, que se desarrollar\u00e1 en el Palacete de la Seda, en la pedan\u00eda murciana de Santa Cruz, durante la jornada del 19 de noviembre. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Primer encuentro de pintura al vino en la Regi\u00f3n de Murcia\" class=\"read-more button\" href=\"https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/#more-5235\" aria-label=\"Leer m\u00e1s sobre Primer encuentro de pintura al vino en la Regi\u00f3n de Murcia\">M\u00e1s informaci\u00f3n<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5235","post","type-post","status-publish","format-standard","hentry","category-general","masonry-post","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pintura al vino<\/title>\n<meta name=\"description\" content=\"La Asociaci\u00f3n Murciana de Cr\u00edticos de Arte, la Fundaci\u00f3n Fuentes\u2010Vicente y la Cofrad\u00eda del Vino Reino de la Monastrell promueven un \u201cPrimer encuentro de pintura al vino en la Regi\u00f3n de Murcia\u201d, que se desarrollar\u00e1 en el Palacete de la Seda, en la pedan\u00eda murciana de Santa Cruz, durante la jornada del 19 de noviembre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Se llama copla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/\",\"url\":\"https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/\",\"name\":\"Pintura al vino\",\"isPartOf\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#website\"},\"datePublished\":\"2011-11-18T12:17:14+00:00\",\"author\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5\"},\"description\":\"La Asociaci\u00f3n Murciana de Cr\u00edticos de Arte, la Fundaci\u00f3n Fuentes\u2010Vicente y la Cofrad\u00eda del Vino Reino de la Monastrell promueven un \u201cPrimer encuentro de pintura al vino en la Regi\u00f3n de Murcia\u201d, que se desarrollar\u00e1 en el Palacete de la Seda, en la pedan\u00eda murciana de Santa Cruz, durante la jornada del 19 de noviembre.\",\"breadcrumb\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/miguelmoreno.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primer encuentro de pintura al vino en la Regi\u00f3n de Murcia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#website\",\"url\":\"https:\/\/miguelmoreno.org\/blog\/\",\"name\":\"El Blog del Sur\",\"description\":\"Cultura, conciertos, ferias, coplas...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/miguelmoreno.org\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5\",\"name\":\"Se llama copla\",\"sameAs\":[\"https:\/\/miguelmoreno.org\/blog\",\"https:\/\/x.com\/coplasandalucia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pintura al vino","description":"La Asociaci\u00f3n Murciana de Cr\u00edticos de Arte, la Fundaci\u00f3n Fuentes\u2010Vicente y la Cofrad\u00eda del Vino Reino de la Monastrell promueven un \u201cPrimer encuentro de pintura al vino en la Regi\u00f3n de Murcia\u201d, que se desarrollar\u00e1 en el Palacete de la Seda, en la pedan\u00eda murciana de Santa Cruz, durante la jornada del 19 de noviembre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/","twitter_misc":{"Escrito por":"Se llama copla","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/","url":"https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/","name":"Pintura al vino","isPartOf":{"@id":"https:\/\/miguelmoreno.org\/blog\/#website"},"datePublished":"2011-11-18T12:17:14+00:00","author":{"@id":"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5"},"description":"La Asociaci\u00f3n Murciana de Cr\u00edticos de Arte, la Fundaci\u00f3n Fuentes\u2010Vicente y la Cofrad\u00eda del Vino Reino de la Monastrell promueven un \u201cPrimer encuentro de pintura al vino en la Regi\u00f3n de Murcia\u201d, que se desarrollar\u00e1 en el Palacete de la Seda, en la pedan\u00eda murciana de Santa Cruz, durante la jornada del 19 de noviembre.","breadcrumb":{"@id":"https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/miguelmoreno.org\/blog\/primer-encuentro-de-pintura-al-vino-en-la-region-de-murcia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/miguelmoreno.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Primer encuentro de pintura al vino en la Regi\u00f3n de Murcia"}]},{"@type":"WebSite","@id":"https:\/\/miguelmoreno.org\/blog\/#website","url":"https:\/\/miguelmoreno.org\/blog\/","name":"El Blog del Sur","description":"Cultura, conciertos, ferias, coplas...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miguelmoreno.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5","name":"Se llama copla","sameAs":["https:\/\/miguelmoreno.org\/blog","https:\/\/x.com\/coplasandalucia"]}]}},"_links":{"self":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts\/5235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/comments?post=5235"}],"version-history":[{"count":0,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts\/5235\/revisions"}],"wp:attachment":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/media?parent=5235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/categories?post=5235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/tags?post=5235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}