{"id":5289,"date":"2011-12-03T23:49:09","date_gmt":"2011-12-03T21:49:09","guid":{"rendered":"http:\/\/www.miguelmoreno.org\/blog\/?p=5289"},"modified":"2021-01-15T17:30:49","modified_gmt":"2021-01-15T15:30:49","slug":"alumbrado-de-navidad-de-granada-2011","status":"publish","type":"post","link":"https:\/\/miguelmoreno.org\/blog\/alumbrado-de-navidad-de-granada-2011\/","title":{"rendered":"Alumbrado de Navidad de Granada 2011"},"content":{"rendered":"<p>El encendido oficial del nuevo <a href=\"http:\/\/arrabal.eu\/navidad\/navidad_granada.html\">alumbrado navide\u00f1o<\/a> de la ciudad de <a href=\"http:\/\/arrabal.eu\/granada\/granada.html\">Granada<\/a> tendr\u00e1 lugar este viernes, d\u00eda 2 de diciembre, a las 19.30 horas en la plaza del Carmen. En esta ocasi\u00f3n, y coincidiendo con la celebraci\u00f3n del Festival de Flamenco de Granada, el acto de encendido arrancar\u00e1 con un espect\u00e1culo flamenco que correr\u00e1 a cargo del bailar\u00edn y director del certamen Juan Andr\u00e9s Maya desde el <a href=\"http:\/\/arrabal.eu\/granada\/caballo.html\">balc\u00f3n de la casa Consistorial<\/a>.<br \/>\nTras la actuaci\u00f3n flamenca, el alcalde de Granada, Jos\u00e9 Torres Hurtado, junto a los patrocinadores del alumbrado, proceder\u00e1n al encendido oficial de las luces navide\u00f1as. En esta ocasi\u00f3n, el Ayuntamiento de Granada ha apostado por un dise\u00f1o de calidad y colorista en el que destaca la recuperaci\u00f3n de la<a href=\"http:\/\/arrabal.eu\/granada\/navidad\/2007\/bib-rambla.html\"> plaza Bib-Rambla<\/a> como entorno familiar y de encuentro.<\/p>\n<p style=\"text-align: center;\"><object data=\"http:\/\/www.youtube.com\/v\/AbnV3MxogGM\" type=\"application\/x-shockwave-flash\" width=\"425\" height=\"350\"><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/AbnV3MxogGM\" \/><\/object><\/p>\n<p>As\u00ed, los viandantes podr\u00e1n disfrutar en este enclave de un abeto de m\u00e1s de 17 metros de altura y 7 de base y de un alumbrado con motivos relacionados con los m\u00e1s peque\u00f1os. A su vez, el alumbrado, que permanecer\u00e1 encendido hasta el d\u00eda 7 de enero en horario de 18.30 horas a las 24.00 horas, con excepci\u00f3n de los d\u00edas 24 y 31, que se apagar\u00e1 a las 2 de la madrugada, estar\u00e1 acompa\u00f1ado en todo momento por un hilo musical con villancicos infantiles.<\/p>\n<p>Este a\u00f1o, la ciudad estar\u00e1 engalanada con m\u00e1s puntos de luz que el a\u00f1o pasado. En concreto, las calles estar\u00e1n iluminadas con un total de 1.500.000 puntos de luz, con un consumo estimado de 370.00 vatios. Tambi\u00e9n en los barrios, el Ayuntamiento de Granada mejora este a\u00f1o el dise\u00f1o y los elementos navide\u00f1os de este alumbrado extraordinario. Los ocho distritos de la ciudad podr\u00e1n disfrutar de 220 arcos con diversidad de figuras, tapices, cordones e hilos luminosos.<\/p>\n<p>La propuesta ha sido posible gracias al esfuerzo de colaboraci\u00f3n de hosteleros y establecimientos de Bib-Rambla, as\u00ed como de otras empresas granadinas que, como La Cueva de 1900, el Bono tur\u00edstico, Emuvyssa, Cervezas Alhambra o El Corte Ingl\u00e9s, asumen esa mayor cantidad de adornos navide\u00f1os y puntos de luz, sin que su instalaci\u00f3n haya supuesto un coste a\u00f1adido a las arcas municipales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El encendido oficial del nuevo alumbrado navide\u00f1o de la ciudad de Granada tendr\u00e1 lugar este viernes, d\u00eda 2 de diciembre, a las 19.30 horas en la plaza del Carmen. En esta ocasi\u00f3n, y coincidiendo con la celebraci\u00f3n del Festival de Flamenco de Granada, el acto de encendido arrancar\u00e1 con un espect\u00e1culo flamenco que correr\u00e1 a &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Alumbrado de Navidad de Granada 2011\" class=\"read-more button\" href=\"https:\/\/miguelmoreno.org\/blog\/alumbrado-de-navidad-de-granada-2011\/#more-5289\" aria-label=\"Leer m\u00e1s sobre Alumbrado de Navidad de Granada 2011\">M\u00e1s informaci\u00f3n<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1484,1485],"tags":[60],"class_list":["post-5289","post","type-post","status-publish","format-standard","hentry","category-granada","category-navidad","tag-navidad","masonry-post","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alumbrado de Navidad de Granada 2011<\/title>\n<meta name=\"description\" content=\"El encendido oficial del nuevo alumbrado navide\u00f1o de la ciudad de Granada tendr\u00e1 lugar este viernes, d\u00eda 2 de diciembre, a las 19.30 horas en la plaza del Carmen. En esta ocasi\u00f3n, y coincidiendo con la celebraci\u00f3n del Festival de Flamenco de Granada, el acto de encendido arrancar\u00e1 con un espect\u00e1culo flamenco que correr\u00e1 a cargo del bailar\u00edn y director del certamen Juan Andr\u00e9s Maya desde el balc\u00f3n de la casa Consistorial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miguelmoreno.org\/blog\/alumbrado-navidad-granada\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Se llama copla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/alumbrado-de-navidad-de-granada-2011\/\",\"url\":\"https:\/\/miguelmoreno.org\/blog\/alumbrado-navidad-granada\/\",\"name\":\"Alumbrado de Navidad de Granada 2011\",\"isPartOf\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#website\"},\"datePublished\":\"2011-12-03T21:49:09+00:00\",\"dateModified\":\"2021-01-15T15:30:49+00:00\",\"author\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5\"},\"description\":\"El encendido oficial del nuevo alumbrado navide\u00f1o de la ciudad de Granada tendr\u00e1 lugar este viernes, d\u00eda 2 de diciembre, a las 19.30 horas en la plaza del Carmen. En esta ocasi\u00f3n, y coincidiendo con la celebraci\u00f3n del Festival de Flamenco de Granada, el acto de encendido arrancar\u00e1 con un espect\u00e1culo flamenco que correr\u00e1 a cargo del bailar\u00edn y director del certamen Juan Andr\u00e9s Maya desde el balc\u00f3n de la casa Consistorial.\",\"breadcrumb\":{\"@id\":\"https:\/\/miguelmoreno.org\/blog\/alumbrado-navidad-granada\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/miguelmoreno.org\/blog\/alumbrado-navidad-granada\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/alumbrado-navidad-granada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/miguelmoreno.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alumbrado de Navidad de Granada 2011\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#website\",\"url\":\"https:\/\/miguelmoreno.org\/blog\/\",\"name\":\"El Blog del Sur\",\"description\":\"Cultura, conciertos, ferias, coplas...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/miguelmoreno.org\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5\",\"name\":\"Se llama copla\",\"sameAs\":[\"https:\/\/miguelmoreno.org\/blog\",\"https:\/\/x.com\/coplasandalucia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alumbrado de Navidad de Granada 2011","description":"El encendido oficial del nuevo alumbrado navide\u00f1o de la ciudad de Granada tendr\u00e1 lugar este viernes, d\u00eda 2 de diciembre, a las 19.30 horas en la plaza del Carmen. En esta ocasi\u00f3n, y coincidiendo con la celebraci\u00f3n del Festival de Flamenco de Granada, el acto de encendido arrancar\u00e1 con un espect\u00e1culo flamenco que correr\u00e1 a cargo del bailar\u00edn y director del certamen Juan Andr\u00e9s Maya desde el balc\u00f3n de la casa Consistorial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miguelmoreno.org\/blog\/alumbrado-navidad-granada\/","twitter_misc":{"Escrito por":"Se llama copla","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/miguelmoreno.org\/blog\/alumbrado-de-navidad-de-granada-2011\/","url":"https:\/\/miguelmoreno.org\/blog\/alumbrado-navidad-granada\/","name":"Alumbrado de Navidad de Granada 2011","isPartOf":{"@id":"https:\/\/miguelmoreno.org\/blog\/#website"},"datePublished":"2011-12-03T21:49:09+00:00","dateModified":"2021-01-15T15:30:49+00:00","author":{"@id":"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5"},"description":"El encendido oficial del nuevo alumbrado navide\u00f1o de la ciudad de Granada tendr\u00e1 lugar este viernes, d\u00eda 2 de diciembre, a las 19.30 horas en la plaza del Carmen. En esta ocasi\u00f3n, y coincidiendo con la celebraci\u00f3n del Festival de Flamenco de Granada, el acto de encendido arrancar\u00e1 con un espect\u00e1culo flamenco que correr\u00e1 a cargo del bailar\u00edn y director del certamen Juan Andr\u00e9s Maya desde el balc\u00f3n de la casa Consistorial.","breadcrumb":{"@id":"https:\/\/miguelmoreno.org\/blog\/alumbrado-navidad-granada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miguelmoreno.org\/blog\/alumbrado-navidad-granada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/miguelmoreno.org\/blog\/alumbrado-navidad-granada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/miguelmoreno.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Alumbrado de Navidad de Granada 2011"}]},{"@type":"WebSite","@id":"https:\/\/miguelmoreno.org\/blog\/#website","url":"https:\/\/miguelmoreno.org\/blog\/","name":"El Blog del Sur","description":"Cultura, conciertos, ferias, coplas...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miguelmoreno.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/miguelmoreno.org\/blog\/#\/schema\/person\/cde8639f19077551d0d59650a04b23d5","name":"Se llama copla","sameAs":["https:\/\/miguelmoreno.org\/blog","https:\/\/x.com\/coplasandalucia"]}]}},"_links":{"self":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts\/5289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/comments?post=5289"}],"version-history":[{"count":2,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts\/5289\/revisions"}],"predecessor-version":[{"id":12240,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/posts\/5289\/revisions\/12240"}],"wp:attachment":[{"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/media?parent=5289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/categories?post=5289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miguelmoreno.org\/blog\/wp-json\/wp\/v2\/tags?post=5289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}